{"id":26300,"date":"2021-11-19T14:40:50","date_gmt":"2021-11-19T17:40:50","guid":{"rendered":"http:\/\/dsrmedios.com.ar\/diario\/?p=26300"},"modified":"2021-11-19T14:40:53","modified_gmt":"2021-11-19T17:40:53","slug":"charla-sobre-seguridad-vial-para-jovenes-en-trama","status":"publish","type":"post","link":"http:\/\/dsrmedios.com.ar\/diario\/archivos\/26300","title":{"rendered":"Charla sobre Seguridad Vial para J\u00f3venes en Trama"},"content":{"rendered":"\n<p>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\nLa Secretar\u00eda de Seguridad\nde la Municipalidad de Adolfo Alsina contin\u00faa ofreciendo charlas sobre\nseguridad vial en todo el distrito.<br><br>\nEn esta ocasi\u00f3n, la oficial Inspectora Noelia Blanco, T\u00e9cnica Superior en\nSeguridad Vial y en Criminal\u00edstica con orientaci\u00f3n en Accidentolog\u00eda Vial, la\nCoordinadora en Educaci\u00f3n Vial, Mariana Ravera, y el Secretario de Seguridad de\nAdolfo Alsina, Facundo Olavarr\u00eda, brindaron una charla a J\u00f3venes en Trama con\nejemplos, proyecciones, conductas viales, reglas, comportamientos para llevar a\ncabo el orden y la seguridad vial.<br><br>\nLa misma se llev\u00f3 a cabo en la localidad de Carhu\u00e9.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>La Secretar\u00eda de Seguridad de la Municipalidad de Adolfo Alsina contin\u00faa ofreciendo charlas sobre seguridad vial en todo el distrito. En esta ocasi\u00f3n, la oficial Inspectora Noelia Blanco, T\u00e9cnica Superior en Seguridad Vial y en Criminal\u00edstica con orientaci\u00f3n en Accidentolog\u00eda Vial, la Coordinadora en Educaci\u00f3n Vial, Mariana Ravera, y el Secretario de Seguridad de Adolfo Alsina, Facundo Olavarr\u00eda, brindaron una charla a J\u00f3venes en Trama con ejemplos, proyecciones, conductas viales, reglas, comportamientos para llevar a cabo el orden y la seguridad vial. La misma se llev\u00f3 a cabo en la localidad de Carhu\u00e9.<\/p>\n<\/div>","protected":false},"author":6,"featured_media":26301,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":""},"categories":[31],"tags":[],"jetpack_featured_media_url":"http:\/\/dsrmedios.com.ar\/diario\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-17-at-08.29.40.jpeg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9fihK-6Qc","_links":{"self":[{"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/posts\/26300"}],"collection":[{"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/comments?post=26300"}],"version-history":[{"count":1,"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/posts\/26300\/revisions"}],"predecessor-version":[{"id":26302,"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/posts\/26300\/revisions\/26302"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/media\/26301"}],"wp:attachment":[{"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/media?parent=26300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/categories?post=26300"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/tags?post=26300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}