{"id":25923,"date":"2021-10-20T07:28:03","date_gmt":"2021-10-20T10:28:03","guid":{"rendered":"http:\/\/dsrmedios.com.ar\/diario\/?p=25923"},"modified":"2021-10-20T07:28:04","modified_gmt":"2021-10-20T10:28:04","slug":"anuncian-la-aplicacion-de-un-monotributo-gratuito","status":"publish","type":"post","link":"http:\/\/dsrmedios.com.ar\/diario\/archivos\/25923","title":{"rendered":"Anuncian la aplicaci\u00f3n de un monotributo gratuito"},"content":{"rendered":"\n<p>El secretario de Econom\u00eda Social dependiente del Ministerio de Desarrollo Social, Emilio P\u00e9rsico, anticip\u00f3 ayer que la soluci\u00f3n de aplicar &#8220;un monotributo totalmente gratuito&#8221; ser\u00e1 para morigerar los efectos de que la informalidad laboral que, en Argentina, alcanza al 50% de la poblaci\u00f3n.<\/p>\n\n\n\n<p>En di\u00e1logo con Urbana Play, el dirigente del Movimiento Evita adelant\u00f3: &#8220;Hay que hacer un proceso de blanqueo. Ma\u00f1ana (por hoy) habr\u00e1 una reivindicaci\u00f3n hist\u00f3rica nuestra y ser\u00e1 una de las m\u00e1s importantes, ya que hay 4 millones de compa\u00f1eros que se han inventado el trabajo y quieren estar en blanco, el problema es que los costos son muy caros&#8221;.<\/p>\n\n\n\n<p>De todas maneras, si bien actualmente existe un monotributo social, su alcance es limitado ya que lo utilizan solamente 600.000 personas en todo el pa\u00eds.<\/p>\n\n\n\n<p>En tanto, el nuevo monotributo ser\u00e1 para trabajadores en estado de precarizaci\u00f3n tendr\u00e1 un mayor alcance y ser\u00e1 gratuito por dos a\u00f1os. Adem\u00e1s, se prev\u00e9 que, en los dos a\u00f1os siguientes, el costo de la cuota sea del 50%.<\/p>\n\n\n\n<p>A su vez, esta nueva manera de formalizaci\u00f3n laboral alcanzar\u00e1, en principio, a quienes est\u00e1n inscriptos en el Registro Nacional de Trabajadores de la Econom\u00eda Popular (Renatrep), que son casi 3 millones de personas.<\/p>\n\n\n\n<p>El anuncio se realizar\u00eda a 25 d\u00edas de los pr\u00f3ximos comicios ya que, seg\u00fan lo estipulado en el C\u00f3digo Nacional Electoral (CNE), a partir de hoy comienza la prohibici\u00f3n de actos p\u00fablicos susceptibles de promover la captaci\u00f3n del sufragio.<\/p>\n\n\n\n<p>En definitiva, esta medida ir\u00e1 en el mismo sentido de la decretada ayer en donde se oficializ\u00f3 por Bolet\u00edn Oficial la reconversi\u00f3n de planes sociales como el Potenciar Trabajo y el Programa de Inserci\u00f3n Laboral en empleos efectivos y registrados.<\/p>\n\n\n\n<p>Con todo, desde el Gobierno se apunta a, adem\u00e1s de sumar adhesiones de cara a las Elecciones Legislativas Generales del 14 de noviembre, reconocer a los sectores m\u00e1s postergados.<\/p>\n\n\n\n<p>fuente:www.infocielo.com<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>El secretario de Econom\u00eda Social dependiente del Ministerio de Desarrollo Social, Emilio P\u00e9rsico, anticip\u00f3 ayer que la soluci\u00f3n de aplicar &#8220;un monotributo totalmente gratuito&#8221; ser\u00e1 para morigerar los efectos de que la informalidad laboral que, en Argentina, alcanza al 50% de la poblaci\u00f3n. En di\u00e1logo con Urbana Play, el dirigente del Movimiento Evita adelant\u00f3: &#8220;Hay que hacer un proceso de blanqueo. Ma\u00f1ana (por hoy) habr\u00e1 una reivindicaci\u00f3n hist\u00f3rica nuestra y ser\u00e1 una de las m\u00e1s importantes, ya que hay 4 millones de compa\u00f1eros que se han inventado el trabajo y quieren estar en blanco, el problema es que los costos <a class=\"mh-excerpt-more\" href=\"http:\/\/dsrmedios.com.ar\/diario\/archivos\/25923\" title=\"Anuncian la aplicaci\u00f3n de un monotributo gratuito\">[Leer m\u00e1s]<\/a><\/p>\n<\/div>","protected":false},"author":5,"featured_media":9380,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":""},"categories":[18,6],"tags":[],"jetpack_featured_media_url":"http:\/\/dsrmedios.com.ar\/diario\/wp-content\/uploads\/2018\/11\/monotributo.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9fihK-6K7","_links":{"self":[{"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/posts\/25923"}],"collection":[{"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/comments?post=25923"}],"version-history":[{"count":1,"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/posts\/25923\/revisions"}],"predecessor-version":[{"id":25924,"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/posts\/25923\/revisions\/25924"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/media\/9380"}],"wp:attachment":[{"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/media?parent=25923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/categories?post=25923"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/tags?post=25923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}