{"id":25771,"date":"2021-10-07T23:36:34","date_gmt":"2021-10-08T02:36:34","guid":{"rendered":"http:\/\/dsrmedios.com.ar\/diario\/?p=25771"},"modified":"2021-10-07T23:36:35","modified_gmt":"2021-10-08T02:36:35","slug":"vacunacion-itinerante-en-villa-maza-28-personas-recibieron-la-vacuna-contra-covid-19","status":"publish","type":"post","link":"http:\/\/dsrmedios.com.ar\/diario\/archivos\/25771","title":{"rendered":"Vacunaci\u00f3n Itinerante en Villa Maza: 28 personas recibieron la vacuna contra Covid-19"},"content":{"rendered":"\n<p>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\nEn el marco de la\nVacunaci\u00f3n Itinerante que se realiza en Adolfo Alsina se aplicaron veinte\nocho&nbsp;dosis a j\u00f3venes y adultos contra Covid-10 en la localidad de Villa\nMaza. &nbsp;Trece de ellos recibieron la primera dosis y quince la segunda.<br><br>\nLa vacunaci\u00f3n se realiz\u00f3 en Club Atl\u00e9tico Ferrocarril Sarmiento.\n\n\n\n<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>En el marco de la Vacunaci\u00f3n Itinerante que se realiza en Adolfo Alsina se aplicaron veinte ocho&nbsp;dosis a j\u00f3venes y adultos contra Covid-10 en la localidad de Villa Maza. &nbsp;Trece de ellos recibieron la primera dosis y quince la segunda. La vacunaci\u00f3n se realiz\u00f3 en Club Atl\u00e9tico Ferrocarril Sarmiento.<\/p>\n<\/div>","protected":false},"author":6,"featured_media":25772,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":""},"categories":[31],"tags":[],"jetpack_featured_media_url":"http:\/\/dsrmedios.com.ar\/diario\/wp-content\/uploads\/2021\/10\/35c3e118-08f0-ce0a-c994-479b5e9c755b.jpeg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9fihK-6HF","_links":{"self":[{"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/posts\/25771"}],"collection":[{"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/comments?post=25771"}],"version-history":[{"count":1,"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/posts\/25771\/revisions"}],"predecessor-version":[{"id":25773,"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/posts\/25771\/revisions\/25773"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/media\/25772"}],"wp:attachment":[{"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/media?parent=25771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/categories?post=25771"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/dsrmedios.com.ar\/diario\/wp-json\/wp\/v2\/tags?post=25771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}